{"id":2629,"date":"2017-10-31T12:00:27","date_gmt":"2017-10-31T11:00:27","guid":{"rendered":"https:\/\/sbkg.eu\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/"},"modified":"2022-07-20T18:58:00","modified_gmt":"2022-07-20T16:58:00","slug":"sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense","status":"publish","type":"post","link":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/","title":{"rendered":"sbkg &#038; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2629\" class=\"elementor elementor-2629 elementor-689\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47e2939a elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"47e2939a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43e15041\" data-id=\"43e15041\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d484fb5 elementor-widget elementor-widget-text-editor\" data-id=\"3d484fb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SBKG &amp; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense, le plus grand immeuble de bureaux d&#8217;Europe par Lone Star \u00e0 Amundi Real Estate, Cr\u00e9dit Agricole des Assurances et Primonial REIM.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SBKG &amp; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2361,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deals-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sbkg &amp; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense - sbkg &amp; associ\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sbkg &amp; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense - sbkg &amp; associ\u00e9s\" \/>\n<meta property=\"og:description\" content=\"SBKG &amp; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/\" \/>\n<meta property=\"og:site_name\" content=\"sbkg &amp; associ\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-31T11:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-20T16:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sbkg.eu\/wp-content\/uploads\/2017\/10\/news-coeur-la-defense.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/\"},\"author\":{\"name\":\"Pierre\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#\\\/schema\\\/person\\\/a8b041330cdcd0953aced59da912cc95\"},\"headline\":\"sbkg &#038; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense\",\"datePublished\":\"2017-10-31T11:00:27+00:00\",\"dateModified\":\"2022-07-20T16:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/\"},\"wordCount\":73,\"publisher\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/news-coeur-la-defense.jpg\",\"articleSection\":[\"Deals\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/\",\"name\":\"sbkg & associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense - sbkg &amp; associ\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/news-coeur-la-defense.jpg\",\"datePublished\":\"2017-10-31T11:00:27+00:00\",\"dateModified\":\"2022-07-20T16:58:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/news-coeur-la-defense.jpg\",\"contentUrl\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/news-coeur-la-defense.jpg\",\"width\":600,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sbkg &#038; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/\",\"name\":\"SBKG\",\"description\":\"Exp\u00e9rience et expertise en droit immobilier et h\u00f4telier\",\"publisher\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#organization\",\"name\":\"SBKG\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo_sbkg.png\",\"contentUrl\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo_sbkg.png\",\"width\":195,\"height\":65,\"caption\":\"SBKG\"},\"image\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#\\\/schema\\\/person\\\/a8b041330cdcd0953aced59da912cc95\",\"name\":\"Pierre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g\",\"caption\":\"Pierre\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sbkg & associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense - sbkg &amp; associ\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/","og_locale":"en_US","og_type":"article","og_title":"sbkg & associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense - sbkg &amp; associ\u00e9s","og_description":"SBKG &amp; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la...","og_url":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/","og_site_name":"sbkg &amp; associ\u00e9s","article_published_time":"2017-10-31T11:00:27+00:00","article_modified_time":"2022-07-20T16:58:00+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/sbkg.eu\/wp-content\/uploads\/2017\/10\/news-coeur-la-defense.jpg","type":"image\/jpeg"}],"author":"Pierre","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pierre"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/#article","isPartOf":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/"},"author":{"name":"Pierre","@id":"https:\/\/sbkg.eu\/en\/#\/schema\/person\/a8b041330cdcd0953aced59da912cc95"},"headline":"sbkg &#038; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense","datePublished":"2017-10-31T11:00:27+00:00","dateModified":"2022-07-20T16:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/"},"wordCount":73,"publisher":{"@id":"https:\/\/sbkg.eu\/en\/#organization"},"image":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/#primaryimage"},"thumbnailUrl":"https:\/\/sbkg.eu\/wp-content\/uploads\/2017\/10\/news-coeur-la-defense.jpg","articleSection":["Deals"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/","url":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/","name":"sbkg & associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense - sbkg &amp; associ\u00e9s","isPartOf":{"@id":"https:\/\/sbkg.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/#primaryimage"},"image":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/#primaryimage"},"thumbnailUrl":"https:\/\/sbkg.eu\/wp-content\/uploads\/2017\/10\/news-coeur-la-defense.jpg","datePublished":"2017-10-31T11:00:27+00:00","dateModified":"2022-07-20T16:58:00+00:00","breadcrumb":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/#primaryimage","url":"https:\/\/sbkg.eu\/wp-content\/uploads\/2017\/10\/news-coeur-la-defense.jpg","contentUrl":"https:\/\/sbkg.eu\/wp-content\/uploads\/2017\/10\/news-coeur-la-defense.jpg","width":600,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/sbkg.eu\/en\/sbkg-associes-a-conseille-cbre-loan-services-ltd-et-les-preteurs-senior-dans-le-cadre-de-la-cession-de-coeur-defense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sbkg.eu\/en\/"},{"@type":"ListItem","position":2,"name":"sbkg &#038; associ\u00e9s a conseill\u00e9 CBRE Loan Services Ltd et les Pr\u00eateurs Senior dans le cadre de la cession de C\u0153ur D\u00e9fense"}]},{"@type":"WebSite","@id":"https:\/\/sbkg.eu\/en\/#website","url":"https:\/\/sbkg.eu\/en\/","name":"SBKG","description":"Exp\u00e9rience et expertise en droit immobilier et h\u00f4telier","publisher":{"@id":"https:\/\/sbkg.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sbkg.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sbkg.eu\/en\/#organization","name":"SBKG","url":"https:\/\/sbkg.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sbkg.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sbkg.eu\/wp-content\/uploads\/2020\/10\/logo_sbkg.png","contentUrl":"https:\/\/sbkg.eu\/wp-content\/uploads\/2020\/10\/logo_sbkg.png","width":195,"height":65,"caption":"SBKG"},"image":{"@id":"https:\/\/sbkg.eu\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sbkg.eu\/en\/#\/schema\/person\/a8b041330cdcd0953aced59da912cc95","name":"Pierre","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g","caption":"Pierre"}}]}},"_links":{"self":[{"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/posts\/2629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/comments?post=2629"}],"version-history":[{"count":2,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/posts\/2629\/revisions"}],"predecessor-version":[{"id":3197,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/posts\/2629\/revisions\/3197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/media\/2361"}],"wp:attachment":[{"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/media?parent=2629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/categories?post=2629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/tags?post=2629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}