{"id":2962,"date":"2021-09-30T13:00:00","date_gmt":"2021-09-30T11:00:00","guid":{"rendered":"https:\/\/sbkg.eu\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/"},"modified":"2022-07-20T18:01:10","modified_gmt":"2022-07-20T16:01:10","slug":"sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior","status":"publish","type":"post","link":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/","title":{"rendered":"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior"},"content":{"rendered":"\n<p>Apr\u00e8s l\u2019arriv\u00e9e de<strong> Lionel Rosenfeld<\/strong> (ex-Gide, Freshfields Bruckhaus Deringer et associ\u00e9 de DLA Piper) en 2020 avec son \u00e9quipe, le cabinet SBKG &amp; associ\u00e9s poursuit son d\u00e9veloppement en accueillant <strong>Carol Santoni<\/strong> et son \u00e9quipe, <strong>Louise Duvernois<\/strong> et <strong>Gw\u00e9nol\u00e9 Morineaux<\/strong>, tous trois experts en op\u00e9rations d\u2019investissements immobiliers ainsi que <strong>Driss Tof<\/strong>, qui cr\u00e9e le d\u00e9partement Fiscalit\u00e9. SBKG &amp; associ\u00e9s compl\u00e8te ainsi sa transformation pour offrir aux investisseurs et op\u00e9rateurs immobiliers et h\u00f4teliers une gamme compl\u00e8te de comp\u00e9tences.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/10\/cs.jpeg\" alt=\"\" class=\"wp-image-15133\"\/><\/figure><\/div>\n\n\n\n<p><strong>Carol&nbsp;Santoni<\/strong>&nbsp;rejoint SBKG&nbsp;&amp; associ\u00e9s&nbsp;en tant qu&#8217;Associ\u00e9e de la pratique \u00ab&nbsp;investissements immobiliers&nbsp;\u00bb. Carol&nbsp;a d\u00e9but\u00e9 sa carri\u00e8re chez Gide (2001 \u00e0 2014) avant de rejoindre Racine en qualit\u00e9 d&#8217;associ\u00e9e&nbsp;en 2014. Carol assiste des acteurs immobiliers de premier plan, fran\u00e7ais ou internationaux, dans leurs op\u00e9rations et plus particuli\u00e8rement, en mati\u00e8re d&#8217;investissements (asset deals,&nbsp;share&nbsp;deals, joint-ventures), de construction et de d\u00e9veloppement (notamment, contrats de promotion immobili\u00e8re et partenariats entre investisseurs et promoteurs). Elle conseille aussi ses clients sur les sujets&nbsp;d&#8217;asset management, notamment en mati\u00e8re de baux commerciaux, et dans leurs projets de restructuration et valorisation sur tous types d&#8217;actifs (bureaux, entrep\u00f4ts, commerces, r\u00e9sidentiels, r\u00e9sidence services et h\u00f4tellerie).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/10\/ld.jpeg\" alt=\"\" class=\"wp-image-15132\"\/><\/figure><\/div>\n\n\n\n<p><strong>Louise&nbsp;Duvernois<\/strong>&nbsp;rejoint SBKG&nbsp;&amp; associ\u00e9s&nbsp;en tant qu&#8217;Associ\u00e9e de la pratique \u00ab&nbsp;investissements immobiliers&nbsp;\u00bb. Louise&nbsp;a d\u00e9but\u00e9 sa carri\u00e8re chez&nbsp;Lacourte&nbsp;Balas &amp; Associ\u00e9s en 2006, avant de rejoindre Gide en 2008,&nbsp;puis White &amp; Case LLP en 2012.&nbsp;En janvier 2020, elle a int\u00e9gr\u00e9 Racine en qualit\u00e9 de&nbsp;Counsel. Elle intervient en mati\u00e8re&nbsp;de transactions immobili\u00e8res (ventes et acquisitions d&#8217;actifs et de portefeuilles immobiliers), de promotion et de construction (notamment, ventes en \u00e9tat futur d&#8217;ach\u00e8vement, contrats de promotion immobili\u00e8re et contrats de ma\u00eetrise d&#8217;ouvrage d\u00e9l\u00e9gu\u00e9e) et d&#8217;asset management. Elle a \u00e9galement d\u00e9velopp\u00e9 une exp\u00e9rience significative en mati\u00e8re de baux commerciaux et assiste&nbsp;\u00e0 ce sujet&nbsp;des acteurs majeurs du march\u00e9 immobilier.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/10\/dt.jpeg\" alt=\"\" class=\"wp-image-15131\"\/><\/figure><\/div>\n\n\n\n<p><strong>Driss&nbsp;Tof<\/strong>&nbsp;rejoint SBKG &amp; associ\u00e9s en tant qu&#8217;Associ\u00e9,&nbsp;cr\u00e9ateur&nbsp;du d\u00e9partement fiscal.&nbsp;Driss a d\u00e9but\u00e9 sa carri\u00e8re chez&nbsp;Arsene&nbsp;Taxand&nbsp;en 2010.&nbsp;Depuis&nbsp;pr\u00e8s&nbsp;de 11 ans, cet expert en fiscalit\u00e9 des soci\u00e9t\u00e9s et fiscalit\u00e9 immobili\u00e8re&nbsp;accompagne une client\u00e8le&nbsp;fran\u00e7aise et internationale&nbsp;d&#8217;investisseurs institutionnels,&nbsp;soci\u00e9t\u00e9s cot\u00e9es,&nbsp;promoteurs&nbsp;immobiliers ou&nbsp;marchands de biens. Il&nbsp;intervient&nbsp;r\u00e9guli\u00e8rement&nbsp;sur des op\u00e9rations de structuration,&nbsp;de&nbsp;cessions\/acquisitions de soci\u00e9t\u00e9s,&nbsp;d&#8217;actifs&nbsp;et de portefeuilles&nbsp;mais aussi&nbsp;dans le cadre de r\u00e9flexions&nbsp;strat\u00e9giques de d\u00e9tention d&#8217;actifs immobiliers.&nbsp;Il a \u00e9galement d\u00e9velopp\u00e9 une exp\u00e9rience significative en mati\u00e8re de fiscalit\u00e9 de l&#8217;urbanisme&nbsp;et de structuration&nbsp;fiscale&nbsp;d&#8217;investissements&nbsp;dans les secteurs de l&#8217;h\u00f4tellerie,&nbsp;para-h\u00f4tellerie, gestion et d\u00e9tention d&#8217;EHPAD&nbsp;ou r\u00e9sidences services.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/10\/gm.jpeg\" alt=\"\" class=\"wp-image-15130\"\/><\/figure><\/div>\n\n\n\n<p><strong>Gw\u00e9nol\u00e9&nbsp;Morineaux<\/strong>&nbsp;rejoint SBKG &amp; associ\u00e9s en tant que Collaborateur Senior de la pratique \u00ab&nbsp;investissements immobiliers&nbsp;\u00bb.&nbsp;Gw\u00e9nol\u00e9&nbsp;a d\u00e9marr\u00e9 sa carri\u00e8re en tant que juriste au sein de diff\u00e9rentes directions juridiques d&#8217;acteurs majeurs de l&#8217;immobilier (Kl\u00e9pierre, Nexity, Unibail-Rodamco-Westfield) avant de rejoindre&nbsp;Lacourte&nbsp;Raquin&nbsp;Tatar en 2016 puis Racine en 2019. Il intervient principalement dans le cadre de dossiers de transactions immobili\u00e8res (acquisition\/cession d&#8217;actifs immobiliers ou de portefeuilles&nbsp;d&#8217;actifs immobiliers) et de gestion de tous types d&#8217;actifs (bureaux, entrep\u00f4ts, commerces, r\u00e9sidentiels, r\u00e9sidences services et h\u00f4tellerie), plus particuli\u00e8rement dans le cadre de la&nbsp;n\u00e9gociation&nbsp;de baux commerciaux.<\/p>\n\n\n\n<p><em>\u00ab&nbsp;Dans le contexte actuel, la sp\u00e9cialisation est une r\u00e9elle valeur ajout\u00e9e.&nbsp;Ces&nbsp;arriv\u00e9es&nbsp;nous permettent&nbsp;d&#8217;\u00eatre op\u00e9rationnels \u00e0 360\u00b0 pour accompagner nos clients tout au long du cycle de vie de leurs actifs immobiliers et h\u00f4teliers. Cabinet ind\u00e9pendant et d\u00e9di\u00e9, nous nous renfor\u00e7ons pour devenir encore plus compl\u00e9mentaires et agiles afin d&#8217;augmenter notre volume d&#8217;activit\u00e9 tout en conservant la m\u00eame capacit\u00e9 de mobilisation.&nbsp;\u00bb<\/em> a d\u00e9clar\u00e9&nbsp;<strong>Vincent Lassalle, Managing Partner de SBKG &amp; associ\u00e9s<\/strong>.<\/p>\n\n\n\n<p><br>\n<p><em>&#8220;Notre objectif est de construire ensemble une nouvelle boutique d\u00e9di\u00e9e au secteur de l&#8217;immobilier d&#8217;entreprises, capable d&#8217;accompagner nos clients dans le d\u00e9veloppement croissant de leurs op\u00e9rations.&#8221;<\/em> a d\u00e9clar\u00e9&nbsp;<strong>Carol&nbsp;Santoni<\/strong>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s l\u2019arriv\u00e9e de Lionel Rosenfeld (ex-Gide, Freshfields Bruckhaus Deringer et associ\u00e9 de DLA Piper) en 2020 avec son&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior - sbkg &amp; associ\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior - sbkg &amp; associ\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s l\u2019arriv\u00e9e de Lionel Rosenfeld (ex-Gide, Freshfields Bruckhaus Deringer et associ\u00e9 de DLA Piper) en 2020 avec son...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/\" \/>\n<meta property=\"og:site_name\" content=\"sbkg &amp; associ\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-20T16:01:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sbkg.eu\/wp-content\/uploads\/2021\/09\/equipiers_cp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"615\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/\"},\"author\":{\"name\":\"Pierre\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#\\\/schema\\\/person\\\/a8b041330cdcd0953aced59da912cc95\"},\"headline\":\"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior\",\"datePublished\":\"2021-09-30T11:00:00+00:00\",\"dateModified\":\"2022-07-20T16:01:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/\"},\"wordCount\":837,\"publisher\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/equipiers_cp.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/\",\"name\":\"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior - sbkg &amp; associ\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/equipiers_cp.jpg\",\"datePublished\":\"2021-09-30T11:00:00+00:00\",\"dateModified\":\"2022-07-20T16:01:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/equipiers_cp.jpg\",\"contentUrl\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/equipiers_cp.jpg\",\"width\":615,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/\",\"name\":\"SBKG\",\"description\":\"Exp\u00e9rience et expertise en droit immobilier et h\u00f4telier\",\"publisher\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#organization\",\"name\":\"SBKG\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo_sbkg.png\",\"contentUrl\":\"https:\\\/\\\/sbkg.eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/logo_sbkg.png\",\"width\":195,\"height\":65,\"caption\":\"SBKG\"},\"image\":{\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sbkg.eu\\\/en\\\/#\\\/schema\\\/person\\\/a8b041330cdcd0953aced59da912cc95\",\"name\":\"Pierre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g\",\"caption\":\"Pierre\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior - sbkg &amp; associ\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/","og_locale":"en_US","og_type":"article","og_title":"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior - sbkg &amp; associ\u00e9s","og_description":"Apr\u00e8s l\u2019arriv\u00e9e de Lionel Rosenfeld (ex-Gide, Freshfields Bruckhaus Deringer et associ\u00e9 de DLA Piper) en 2020 avec son...","og_url":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/","og_site_name":"sbkg &amp; associ\u00e9s","article_published_time":"2021-09-30T11:00:00+00:00","article_modified_time":"2022-07-20T16:01:10+00:00","og_image":[{"width":615,"height":375,"url":"https:\/\/sbkg.eu\/wp-content\/uploads\/2021\/09\/equipiers_cp.jpg","type":"image\/jpeg"}],"author":"Pierre","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pierre","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/#article","isPartOf":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/"},"author":{"name":"Pierre","@id":"https:\/\/sbkg.eu\/en\/#\/schema\/person\/a8b041330cdcd0953aced59da912cc95"},"headline":"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior","datePublished":"2021-09-30T11:00:00+00:00","dateModified":"2022-07-20T16:01:10+00:00","mainEntityOfPage":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/"},"wordCount":837,"publisher":{"@id":"https:\/\/sbkg.eu\/en\/#organization"},"image":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/#primaryimage"},"thumbnailUrl":"https:\/\/sbkg.eu\/wp-content\/uploads\/2021\/09\/equipiers_cp.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/","url":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/","name":"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior - sbkg &amp; associ\u00e9s","isPartOf":{"@id":"https:\/\/sbkg.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/#primaryimage"},"image":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/#primaryimage"},"thumbnailUrl":"https:\/\/sbkg.eu\/wp-content\/uploads\/2021\/09\/equipiers_cp.jpg","datePublished":"2021-09-30T11:00:00+00:00","dateModified":"2022-07-20T16:01:10+00:00","breadcrumb":{"@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/#primaryimage","url":"https:\/\/sbkg.eu\/wp-content\/uploads\/2021\/09\/equipiers_cp.jpg","contentUrl":"https:\/\/sbkg.eu\/wp-content\/uploads\/2021\/09\/equipiers_cp.jpg","width":615,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/sbkg.eu\/en\/sbkg-complete-sa-transformation-et-accelere-son-developpementen-accueillant-trois-nouveaux-associes-et-un-collaborateur-senior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sbkg.eu\/en\/"},{"@type":"ListItem","position":2,"name":"sbkg compl\u00e8te sa transformation et acc\u00e9l\u00e8re son d\u00e9veloppement en accueillant trois nouveaux associ\u00e9s et un collaborateur senior"}]},{"@type":"WebSite","@id":"https:\/\/sbkg.eu\/en\/#website","url":"https:\/\/sbkg.eu\/en\/","name":"SBKG","description":"Exp\u00e9rience et expertise en droit immobilier et h\u00f4telier","publisher":{"@id":"https:\/\/sbkg.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sbkg.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sbkg.eu\/en\/#organization","name":"SBKG","url":"https:\/\/sbkg.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sbkg.eu\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sbkg.eu\/wp-content\/uploads\/2020\/10\/logo_sbkg.png","contentUrl":"https:\/\/sbkg.eu\/wp-content\/uploads\/2020\/10\/logo_sbkg.png","width":195,"height":65,"caption":"SBKG"},"image":{"@id":"https:\/\/sbkg.eu\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sbkg.eu\/en\/#\/schema\/person\/a8b041330cdcd0953aced59da912cc95","name":"Pierre","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/100587199294e53e8aea4960fc134f1e1ba3c9de8118fa131b9b87a7d1b1772d?s=96&d=mm&r=g","caption":"Pierre"}}]}},"_links":{"self":[{"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/posts\/2962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/comments?post=2962"}],"version-history":[{"count":5,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/posts\/2962\/revisions"}],"predecessor-version":[{"id":3167,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/posts\/2962\/revisions\/3167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/media\/2979"}],"wp:attachment":[{"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/media?parent=2962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/categories?post=2962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbkg.eu\/en\/wp-json\/wp\/v2\/tags?post=2962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}